{"id":2455,"date":"2019-12-12T08:56:55","date_gmt":"2019-12-12T08:56:55","guid":{"rendered":"http:\/\/source.wpopal.com\/erios\/hotel-term-condition\/"},"modified":"2019-12-12T08:56:55","modified_gmt":"2019-12-12T08:56:55","slug":"hotel-term-condition-2","status":"publish","type":"page","link":"https:\/\/eccopts.ca\/trinity-centre\/hotel-term-condition-2\/","title":{"rendered":"Terms and Conditions"},"content":{"rendered":"<p>Something notices<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Something notices<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-2455","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Terms and Conditions - Trinity Centre<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eccopts.ca\/trinity-centre\/hotel-term-condition-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Terms and Conditions - Trinity Centre\" \/>\n<meta property=\"og:description\" content=\"Something notices\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eccopts.ca\/trinity-centre\/hotel-term-condition-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Trinity Centre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eccopts.ca\/trinity-centre\/hotel-term-condition-2\/\",\"url\":\"https:\/\/eccopts.ca\/trinity-centre\/hotel-term-condition-2\/\",\"name\":\"Terms and Conditions - Trinity Centre\",\"isPartOf\":{\"@id\":\"https:\/\/eccopts.ca\/trinity-centre\/#website\"},\"datePublished\":\"2019-12-12T08:56:55+00:00\",\"dateModified\":\"2019-12-12T08:56:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/eccopts.ca\/trinity-centre\/hotel-term-condition-2\/#breadcrumb\"},\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eccopts.ca\/trinity-centre\/hotel-term-condition-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eccopts.ca\/trinity-centre\/hotel-term-condition-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/eccopts.ca\/trinity-centre\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Terms and Conditions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eccopts.ca\/trinity-centre\/#website\",\"url\":\"https:\/\/eccopts.ca\/trinity-centre\/\",\"name\":\"Trinity Centre\",\"description\":\"ECCOPTS - Trinity Centre\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/eccopts.ca\/trinity-centre\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Terms and Conditions - Trinity Centre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eccopts.ca\/trinity-centre\/hotel-term-condition-2\/","og_locale":"en_US","og_type":"article","og_title":"Terms and Conditions - Trinity Centre","og_description":"Something notices","og_url":"https:\/\/eccopts.ca\/trinity-centre\/hotel-term-condition-2\/","og_site_name":"Trinity Centre","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eccopts.ca\/trinity-centre\/hotel-term-condition-2\/","url":"https:\/\/eccopts.ca\/trinity-centre\/hotel-term-condition-2\/","name":"Terms and Conditions - Trinity Centre","isPartOf":{"@id":"https:\/\/eccopts.ca\/trinity-centre\/#website"},"datePublished":"2019-12-12T08:56:55+00:00","dateModified":"2019-12-12T08:56:55+00:00","breadcrumb":{"@id":"https:\/\/eccopts.ca\/trinity-centre\/hotel-term-condition-2\/#breadcrumb"},"inLanguage":"en-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eccopts.ca\/trinity-centre\/hotel-term-condition-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/eccopts.ca\/trinity-centre\/hotel-term-condition-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eccopts.ca\/trinity-centre\/"},{"@type":"ListItem","position":2,"name":"Terms and Conditions"}]},{"@type":"WebSite","@id":"https:\/\/eccopts.ca\/trinity-centre\/#website","url":"https:\/\/eccopts.ca\/trinity-centre\/","name":"Trinity Centre","description":"ECCOPTS - Trinity Centre","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eccopts.ca\/trinity-centre\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"}]}},"_links":{"self":[{"href":"https:\/\/eccopts.ca\/trinity-centre\/wp-json\/wp\/v2\/pages\/2455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eccopts.ca\/trinity-centre\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/eccopts.ca\/trinity-centre\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/eccopts.ca\/trinity-centre\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eccopts.ca\/trinity-centre\/wp-json\/wp\/v2\/comments?post=2455"}],"version-history":[{"count":0,"href":"https:\/\/eccopts.ca\/trinity-centre\/wp-json\/wp\/v2\/pages\/2455\/revisions"}],"wp:attachment":[{"href":"https:\/\/eccopts.ca\/trinity-centre\/wp-json\/wp\/v2\/media?parent=2455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}